{"id":6630,"date":"2026-04-11T05:09:08","date_gmt":"2026-04-11T05:09:08","guid":{"rendered":"https:\/\/viverocactus.com.mx\/?post_type=product&#038;p=6630"},"modified":"2026-06-15T22:13:06","modified_gmt":"2026-06-15T22:13:06","slug":"huernia-pillamsii-x-pendula-3","status":"publish","type":"product","link":"https:\/\/viverocactus.com.mx\/index.php\/product\/huernia-pillamsii-x-pendula-3\/","title":{"rendered":"Huernia pillamsii x pendula 3&#8243;"},"content":{"rendered":"<p>Im\u00e1genes de referencia<\/p>\n<p>Algunas im\u00e1genes mostradas en este sitio web corresponden a ejemplares en etapa adulta o en floraci\u00f3n y se utilizan \u00fanicamente como referencia para mostrar el potencial de crecimiento, forma y floraci\u00f3n de cada especie.<\/p>\n<p>Las plantas que se env\u00edan corresponden a ejemplares j\u00f3venes, en el tama\u00f1o y etapa de desarrollo especificados en la descripci\u00f3n del producto.<br \/>\nCada planta es un organismo vivo y puede presentar variaciones naturales en forma, tama\u00f1o y color.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im\u00e1genes de referencia Algunas im\u00e1genes mostradas en este sitio web corresponden a ejemplares en etapa adulta o en floraci\u00f3n y se utilizan \u00fanicamente como referencia para mostrar el potencial de crecimiento, forma y floraci\u00f3n de cada especie. Las plantas que se env\u00edan corresponden a ejemplares j\u00f3venes, en el tama\u00f1o y etapa de desarrollo especificados en [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[59],"product_tag":[],"class_list":["post-6630","product","type-product","status-publish","product_cat-africana","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"_links":{"self":[{"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/product\/6630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6630"}],"wp:attachment":[{"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6630"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/product_brand?post=6630"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=6630"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/viverocactus.com.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=6630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}